{"id":2514,"count":7,"description":"","link":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/","name":"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a","slug":"%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a","taxonomy":"category","parent":2510,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a - Guide Of Antalya<\/title>\n<meta name=\"description\" content=\"- Guide Of Antalya\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a - Guide Of Antalya\" \/>\n<meta property=\"og:description\" content=\"- Guide Of Antalya\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/\" \/>\n<meta property=\"og:site_name\" content=\"Guide Of Antalya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/category\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\\\/\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/category\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\\\/\",\"name\":\"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a - Guide Of Antalya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/#website\"},\"description\":\"- Guide Of Antalya\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/category\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/category\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/about-us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/category\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0627\u0646\u0637\u0627\u0644\u064a\u0627\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/category\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\\\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/\",\"name\":\"Guide Of Antalya\",\"description\":\"Real Estate and more\",\"publisher\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/#organization\",\"name\":\"Guide Of Antalya\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GOA-Logo.jpeg\",\"contentUrl\":\"https:\\\/\\\/guideofantalya.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GOA-Logo.jpeg\",\"width\":400,\"height\":400,\"caption\":\"Guide Of Antalya\"},\"image\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GuideOfAntalya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a - Guide Of Antalya","description":"- Guide Of Antalya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a - Guide Of Antalya","og_description":"- Guide Of Antalya","og_url":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/","og_site_name":"Guide Of Antalya","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/","url":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/","name":"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a - Guide Of Antalya","isPartOf":{"@id":"https:\/\/guideofantalya.com\/ar\/#website"},"description":"- Guide Of Antalya","breadcrumb":{"@id":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d9%83%d9%88%d9%86%d9%8a%d8%a7%d9%84%d8%aa%d9%8a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/guideofantalya.com\/ar\/about-us\/"},{"@type":"ListItem","position":2,"name":"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a","item":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/"},{"@type":"ListItem","position":3,"name":"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0627\u0646\u0637\u0627\u0644\u064a\u0627","item":"https:\/\/guideofantalya.com\/ar\/category\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa\/%d8%b5%d9%8a%d8%a7%d9%86%d8%a9-%d8%b3%d8%a8%d9%84%d8%aa-%d9%81%d9%8a-%d8%a7%d9%86%d8%b7%d8%a7%d9%84%d9%8a%d8%a7\/"},{"@type":"ListItem","position":4,"name":"\u0635\u064a\u0627\u0646\u0629 \u0633\u0628\u0644\u062a \u0641\u064a \u0643\u0648\u0646\u064a\u0627\u0644\u062a\u064a"}]},{"@type":"WebSite","@id":"https:\/\/guideofantalya.com\/ar\/#website","url":"https:\/\/guideofantalya.com\/ar\/","name":"Guide Of Antalya","description":"Real Estate and more","publisher":{"@id":"https:\/\/guideofantalya.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guideofantalya.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/guideofantalya.com\/ar\/#organization","name":"Guide Of Antalya","url":"https:\/\/guideofantalya.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/guideofantalya.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/guideofantalya.com\/wp-content\/uploads\/2021\/03\/GOA-Logo.jpeg","contentUrl":"https:\/\/guideofantalya.com\/wp-content\/uploads\/2021\/03\/GOA-Logo.jpeg","width":400,"height":400,"caption":"Guide Of Antalya"},"image":{"@id":"https:\/\/guideofantalya.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GuideOfAntalya"]}]}},"_links":{"self":[{"href":"https:\/\/guideofantalya.com\/ar\/wp-json\/wp\/v2\/categories\/2514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guideofantalya.com\/ar\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/guideofantalya.com\/ar\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/guideofantalya.com\/ar\/wp-json\/wp\/v2\/categories\/2510"}],"wp:post_type":[{"href":"https:\/\/guideofantalya.com\/ar\/wp-json\/wp\/v2\/posts?categories=2514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}