{"id":3005,"count":1,"description":"","link":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/","name":"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632","slug":"%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2","taxonomy":"category","parent":2997,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632 - Guide Of Antalya<\/title>\n<meta name=\"description\" content=\"- Guide Of Antalya\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632 - Guide Of Antalya\" \/>\n<meta property=\"og:description\" content=\"- Guide Of Antalya\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/\" \/>\n<meta property=\"og:site_name\" content=\"Guide Of Antalya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/category\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\\\/\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/category\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\\\/\",\"name\":\"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632 - Guide Of Antalya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/#website\"},\"description\":\"- Guide Of Antalya\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/category\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\\\/#breadcrumb\"},\"inLanguage\":\"fa-IR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/category\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/about-us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u062a\u0631\u06a9\u06cc\u0647\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/category\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u0622\u0646\u062a\u0627\u0644\u06cc\u0627\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/category\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\\\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/\",\"name\":\"Guide Of Antalya\",\"description\":\"Real Estate and more\",\"publisher\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/#organization\",\"name\":\"Guide Of Antalya\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GOA-Logo.jpeg\",\"contentUrl\":\"https:\\\/\\\/guideofantalya.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GOA-Logo.jpeg\",\"width\":400,\"height\":400,\"caption\":\"Guide Of Antalya\"},\"image\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GuideOfAntalya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632 - Guide Of Antalya","description":"- Guide Of Antalya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/","og_locale":"fa_IR","og_type":"article","og_title":"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632 - Guide Of Antalya","og_description":"- Guide Of Antalya","og_url":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/","og_site_name":"Guide Of Antalya","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/","url":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/","name":"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632 - Guide Of Antalya","isPartOf":{"@id":"https:\/\/guideofantalya.com\/fa\/#website"},"description":"- Guide Of Antalya","breadcrumb":{"@id":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/#breadcrumb"},"inLanguage":"fa-IR"},{"@type":"BreadcrumbList","@id":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%da%a9%d9%be%d8%b2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/guideofantalya.com\/fa\/about-us\/"},{"@type":"ListItem","position":2,"name":"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u062a\u0631\u06a9\u06cc\u0647","item":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/"},{"@type":"ListItem","position":3,"name":"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u0622\u0646\u062a\u0627\u0644\u06cc\u0627","item":"https:\/\/guideofantalya.com\/fa\/category\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%aa%d8%b1%da%a9%db%8c%d9%87\/%d8%aa%d8%b1%d8%ac%d9%85%d9%87-%d9%87%d9%86%d8%af%db%8c-%d8%af%d8%b1-%d8%a2%d9%86%d8%aa%d8%a7%d9%84%db%8c%d8%a7\/"},{"@type":"ListItem","position":4,"name":"\u062a\u0631\u062c\u0645\u0647 \u0647\u0646\u062f\u06cc \u062f\u0631 \u06a9\u067e\u0632"}]},{"@type":"WebSite","@id":"https:\/\/guideofantalya.com\/fa\/#website","url":"https:\/\/guideofantalya.com\/fa\/","name":"Guide Of Antalya","description":"Real Estate and more","publisher":{"@id":"https:\/\/guideofantalya.com\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guideofantalya.com\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/guideofantalya.com\/fa\/#organization","name":"Guide Of Antalya","url":"https:\/\/guideofantalya.com\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/guideofantalya.com\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/guideofantalya.com\/wp-content\/uploads\/2021\/03\/GOA-Logo.jpeg","contentUrl":"https:\/\/guideofantalya.com\/wp-content\/uploads\/2021\/03\/GOA-Logo.jpeg","width":400,"height":400,"caption":"Guide Of Antalya"},"image":{"@id":"https:\/\/guideofantalya.com\/fa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GuideOfAntalya"]}]}},"_links":{"self":[{"href":"https:\/\/guideofantalya.com\/fa\/wp-json\/wp\/v2\/categories\/3005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guideofantalya.com\/fa\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/guideofantalya.com\/fa\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/guideofantalya.com\/fa\/wp-json\/wp\/v2\/categories\/2997"}],"wp:post_type":[{"href":"https:\/\/guideofantalya.com\/fa\/wp-json\/wp\/v2\/posts?categories=3005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}