{"id":1120,"count":16,"description":"P\u0131narba\u015f\u0131'nda Sat\u0131l\u0131k Daire","link":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/","name":"P\u0131narba\u015f\u0131'nda Sat\u0131l\u0131k Daire","slug":"pinarbasinda-satilik-daire","taxonomy":"category","parent":1112,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u0131narba\u015f\u0131&#039;nda Sat\u0131l\u0131k Daire - Guide Of Antalya<\/title>\n<meta name=\"description\" content=\"- Guide Of Antalya\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u0131narba\u015f\u0131&#039;nda Sat\u0131l\u0131k Daire - Guide Of Antalya\" \/>\n<meta property=\"og:description\" content=\"- Guide Of Antalya\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/\" \/>\n<meta property=\"og:site_name\" content=\"Guide Of Antalya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/category\\\/turkiyede-satilik-daire\\\/antalyada-satilik-daire\\\/konyaaltinda-satilik-daire\\\/pinarbasinda-satilik-daire\\\/\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/category\\\/turkiyede-satilik-daire\\\/antalyada-satilik-daire\\\/konyaaltinda-satilik-daire\\\/pinarbasinda-satilik-daire\\\/\",\"name\":\"P\u0131narba\u015f\u0131'nda Sat\u0131l\u0131k Daire - Guide Of Antalya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/#website\"},\"description\":\"- Guide Of Antalya\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/category\\\/turkiyede-satilik-daire\\\/antalyada-satilik-daire\\\/konyaaltinda-satilik-daire\\\/pinarbasinda-satilik-daire\\\/#breadcrumb\"},\"inLanguage\":\"tr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/category\\\/turkiyede-satilik-daire\\\/antalyada-satilik-daire\\\/konyaaltinda-satilik-daire\\\/pinarbasinda-satilik-daire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/about-us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00fcrkiye'de Sat\u0131l\u0131k Daire\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/category\\\/turkiyede-satilik-daire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antalya'da Sat\u0131l\u0131k Daire\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/category\\\/turkiyede-satilik-daire\\\/antalyada-satilik-daire\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Konyaalt\u0131'nda Sat\u0131l\u0131k Daire\",\"item\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/category\\\/turkiyede-satilik-daire\\\/antalyada-satilik-daire\\\/konyaaltinda-satilik-daire\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"P\u0131narba\u015f\u0131'nda Sat\u0131l\u0131k Daire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/\",\"name\":\"Guide Of Antalya\",\"description\":\"Real Estate and more\",\"publisher\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/#organization\",\"name\":\"Guide Of Antalya\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/guideofantalya.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GOA-Logo.jpeg\",\"contentUrl\":\"https:\\\/\\\/guideofantalya.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GOA-Logo.jpeg\",\"width\":400,\"height\":400,\"caption\":\"Guide Of Antalya\"},\"image\":{\"@id\":\"https:\\\/\\\/guideofantalya.com\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GuideOfAntalya\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u0131narba\u015f\u0131'nda Sat\u0131l\u0131k Daire - Guide Of Antalya","description":"- Guide Of Antalya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/","og_locale":"tr_TR","og_type":"article","og_title":"P\u0131narba\u015f\u0131'nda Sat\u0131l\u0131k Daire - Guide Of Antalya","og_description":"- Guide Of Antalya","og_url":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/","og_site_name":"Guide Of Antalya","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/","url":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/","name":"P\u0131narba\u015f\u0131'nda Sat\u0131l\u0131k Daire - Guide Of Antalya","isPartOf":{"@id":"https:\/\/guideofantalya.com\/tr\/#website"},"description":"- Guide Of Antalya","breadcrumb":{"@id":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/#breadcrumb"},"inLanguage":"tr"},{"@type":"BreadcrumbList","@id":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/pinarbasinda-satilik-daire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/guideofantalya.com\/tr\/about-us\/"},{"@type":"ListItem","position":2,"name":"T\u00fcrkiye'de Sat\u0131l\u0131k Daire","item":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/"},{"@type":"ListItem","position":3,"name":"Antalya'da Sat\u0131l\u0131k Daire","item":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/"},{"@type":"ListItem","position":4,"name":"Konyaalt\u0131'nda Sat\u0131l\u0131k Daire","item":"https:\/\/guideofantalya.com\/tr\/category\/turkiyede-satilik-daire\/antalyada-satilik-daire\/konyaaltinda-satilik-daire\/"},{"@type":"ListItem","position":5,"name":"P\u0131narba\u015f\u0131'nda Sat\u0131l\u0131k Daire"}]},{"@type":"WebSite","@id":"https:\/\/guideofantalya.com\/tr\/#website","url":"https:\/\/guideofantalya.com\/tr\/","name":"Guide Of Antalya","description":"Real Estate and more","publisher":{"@id":"https:\/\/guideofantalya.com\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guideofantalya.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/guideofantalya.com\/tr\/#organization","name":"Guide Of Antalya","url":"https:\/\/guideofantalya.com\/tr\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/guideofantalya.com\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/guideofantalya.com\/wp-content\/uploads\/2021\/03\/GOA-Logo.jpeg","contentUrl":"https:\/\/guideofantalya.com\/wp-content\/uploads\/2021\/03\/GOA-Logo.jpeg","width":400,"height":400,"caption":"Guide Of Antalya"},"image":{"@id":"https:\/\/guideofantalya.com\/tr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GuideOfAntalya"]}]}},"_links":{"self":[{"href":"https:\/\/guideofantalya.com\/tr\/wp-json\/wp\/v2\/categories\/1120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guideofantalya.com\/tr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/guideofantalya.com\/tr\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/guideofantalya.com\/tr\/wp-json\/wp\/v2\/categories\/1112"}],"wp:post_type":[{"href":"https:\/\/guideofantalya.com\/tr\/wp-json\/wp\/v2\/posts?categories=1120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}